{"id":3078,"date":"2024-06-21T17:29:34","date_gmt":"2024-06-21T09:29:34","guid":{"rendered":"https:\/\/jinruipaper.com\/?p=3078"},"modified":"2024-09-06T16:35:46","modified_gmt":"2024-09-06T08:35:46","slug":"what-is-bamboo-paper-pulp-used-for","status":"publish","type":"post","link":"https:\/\/jinruipaper.com\/pl\/do-czego-jest-uzywana-bambusowa-miazga-papierowa\/","title":{"rendered":"Do czego wykorzystuje si\u0119 bambusow\u0105 mas\u0119 papierow\u0105?"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"3078\" class=\"elementor elementor-3078\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-55d6d9c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55d6d9c\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1822b48\" data-id=\"1822b48\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5f3366 elementor-widget elementor-widget-ha-breadcrumbs happy-addon ha-breadcrumbs happy-addon-pro\" data-id=\"c5f3366\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"ha-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<ul class=\"ha-breadcrumbs\"><li class=\"ha-breadcrumbs-item ha-breadcrumbs-start\"><a href=\"https:\/\/jinruipaper.com\/pl\/\" rel=\"home\"><span class=\"ha-breadcrumbs-text\"><span class=\"ha-breadcrumbs-home-icon\"><span class=\"fas fa-home\" aria-hidden=\"true\"><\/span><\/span>Dom<\/span><\/a><\/li><\/ul>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4380479 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4380479\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c11a44\" data-id=\"2c11a44\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7fbbfc elementor-widget elementor-widget-heading\" data-id=\"d7fbbfc\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Do czego wykorzystuje si\u0119 bambusow\u0105 mas\u0119 papierow\u0105?<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a195ec1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a195ec1\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-87dfae5\" data-id=\"87dfae5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41299f4 elementor-widget elementor-widget-text-editor\" data-id=\"41299f4\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/jinruipaper.com\/pl\/category\/product\/paper-pulp\/bamboo-pulp\/\" target=\"_blank\" rel=\"noopener sponsored\">Masa papierowa bambusowa<\/a> to rodzaj masy celulozowej wykonanej z materia\u0142\u00f3w bambusowych, takich jak bambus Mao, bambus Nan i bambus Ci. Nasza fabryka wykorzystuje do jego produkcji metod\u0119 siarczanow\u0105. Miazga bambusowa ma \u015bredniej d\u0142ugo\u015bci w\u0142\u00f3kna, jest delikatna i mi\u0119kka. Arkusze masy celulozowej s\u0105 grube i maj\u0105 wysok\u0105 odporno\u015b\u0107 na rozdzieranie, chocia\u017c ich wytrzyma\u0142o\u015b\u0107 na rozerwanie i wytrzyma\u0142o\u015b\u0107 na rozci\u0105ganie s\u0105 stosunkowo niskie. Ma wysok\u0105 wytrzyma\u0142o\u015b\u0107 mechaniczn\u0105 i r\u00f3\u017cnorodne zastosowania.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-32865fa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"32865fa\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dc302f4\" data-id=\"dc302f4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-620ec60 elementor-widget elementor-widget-text-editor\" data-id=\"620ec60\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>1. Papiernictwo: Masa papierowa bambusowa jest szeroko stosowana do produkcji r\u00f3\u017cnych rodzaj\u00f3w papieru.\u00a0<\/p><p>Papier kulturowy: obejmuje papier listowy, papier drukarski i papier ksi\u0105\u017ckowy. Miazga bambusowa ma d\u0142ugie w\u0142\u00f3kna i wysok\u0105 wytrzyma\u0142o\u015b\u0107, dzi\u0119ki czemu powstaje g\u0142adki i trwa\u0142y papier odpowiedni do wysokiej jako\u015bci druku.<\/p><p>Papier toaletowy: Papier z pulpy bambusowej jest mi\u0119kki, ch\u0142onny i naturalnie antybakteryjny, dzi\u0119ki czemu idealnie nadaje si\u0119 do papieru toaletowego, chusteczek i innych produkt\u00f3w sanitarnych.<\/p><p>Papier opakowaniowy: Miazg\u0119 papierow\u0105 bambusow\u0105 mo\u017cna r\u00f3wnie\u017c wykorzysta\u0107 do produkcji papieru i tektury opakowaniowej, kt\u00f3re s\u0105 mocne i odporne na rozdarcie, odpowiednie do produkcji toreb papierowych, pude\u0142 i innych materia\u0142\u00f3w opakowaniowych.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a9e4857 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a9e4857\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a7a673\" data-id=\"1a7a673\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-597756b elementor-widget elementor-widget-image\" data-id=\"597756b\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/jinruipaper.com\/wp-content\/uploads\/2024\/06\/corona-4970798_1280-1024x682.jpg\" class=\"attachment-large size-large wp-image-3082\" alt=\"papier toaletowy z bambusa\" srcset=\"https:\/\/jinruipaper.com\/wp-content\/uploads\/2024\/06\/corona-4970798_1280-1024x682.jpg 1024w, https:\/\/jinruipaper.com\/wp-content\/uploads\/2024\/06\/corona-4970798_1280-300x200.jpg 300w, https:\/\/jinruipaper.com\/wp-content\/uploads\/2024\/06\/corona-4970798_1280-768x512.jpg 768w, https:\/\/jinruipaper.com\/wp-content\/uploads\/2024\/06\/corona-4970798_1280-18x12.jpg 18w, https:\/\/jinruipaper.com\/wp-content\/uploads\/2024\/06\/corona-4970798_1280.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15a5efb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"15a5efb\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-674f376\" data-id=\"674f376\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68b1224 elementor-widget elementor-widget-text-editor\" data-id=\"68b1224\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>2. Tekstylia: Pulp\u0119 bambusow\u0105 mo\u017cna dalej przetwarza\u0107 na pulp\u0119 bambusow\u0105 dla przemys\u0142u tekstylnego.<\/p><p>Odzie\u017c: tkanina z w\u0142\u00f3kna bambusowego jest oddychaj\u0105ca, odprowadza wilgo\u0107 i antybakteryjna, idealna na bielizn\u0119, T-shirty, skarpetki i nie tylko. To wygodne i ekologiczne.<\/p><p>Po\u015bciel: Mi\u0119kko\u015b\u0107 i ch\u0142onno\u015b\u0107 w\u0142\u00f3kna bambusowego sprawiaj\u0105, \u017ce idealnie nadaje si\u0119 na prze\u015bcierad\u0142a, poszwy na ko\u0142dry i poszewki na poduszki, zapewniaj\u0105c komfort i higien\u0119.<\/p><p>R\u0119czniki i r\u0119czniki k\u0105pielowe: R\u0119czniki z w\u0142\u00f3kna bambusowego s\u0105 nie tylko mi\u0119kkie, ale tak\u017ce bardzo ch\u0142onne i antybakteryjne, dzi\u0119ki czemu nadaj\u0105 si\u0119 do r\u0119cznik\u00f3w k\u0105pielowych, r\u0119cznik\u00f3w do twarzy i innych produkt\u00f3w do higieny osobistej.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-139a086 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"139a086\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e05c201\" data-id=\"e05c201\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ddb31d9 elementor-widget elementor-widget-image\" data-id=\"ddb31d9\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/jinruipaper.com\/wp-content\/uploads\/2024\/06\/vq7KuEm5BGyRIaayiGTwAQ.jpg\" class=\"attachment-large size-large wp-image-3083\" alt=\"r\u0119cznik z w\u0142\u00f3kna bambusowego\" srcset=\"https:\/\/jinruipaper.com\/wp-content\/uploads\/2024\/06\/vq7KuEm5BGyRIaayiGTwAQ.jpg 800w, https:\/\/jinruipaper.com\/wp-content\/uploads\/2024\/06\/vq7KuEm5BGyRIaayiGTwAQ-300x300.jpg 300w, https:\/\/jinruipaper.com\/wp-content\/uploads\/2024\/06\/vq7KuEm5BGyRIaayiGTwAQ-150x150.jpg 150w, https:\/\/jinruipaper.com\/wp-content\/uploads\/2024\/06\/vq7KuEm5BGyRIaayiGTwAQ-768x768.jpg 768w, https:\/\/jinruipaper.com\/wp-content\/uploads\/2024\/06\/vq7KuEm5BGyRIaayiGTwAQ-12x12.jpg 12w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-00c4ab8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"00c4ab8\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-214669e\" data-id=\"214669e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e456e9f elementor-widget elementor-widget-text-editor\" data-id=\"e456e9f\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>3. Ekologiczne produkty biodegradowalne:<\/p><p>Jednorazowe zastawy sto\u0142owe: Z masy papierowej bambusa mo\u017cna wytwarza\u0107 jednorazowe zastawy sto\u0142owe, takie jak talerze, no\u017ce i widelce, kt\u00f3re s\u0105 nie tylko przyjazne dla \u015brodowiska, ale tak\u017ce mocne i trwa\u0142e.<\/p><p>Materia\u0142y opakowaniowe: Bambusowa masa papierowa jest stosowana w r\u00f3\u017cnych przemys\u0142owych materia\u0142ach opakowaniowych, co zapewnia korzy\u015bci dla \u015brodowiska i zmniejsza zanieczyszczenie tworzywami sztucznymi.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e7cab51 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e7cab51\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4103f6e\" data-id=\"4103f6e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3498f0a elementor-widget elementor-widget-image\" data-id=\"3498f0a\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"781\" src=\"https:\/\/jinruipaper.com\/wp-content\/uploads\/2024\/06\/humbruger-clamshell-1-1.jpg\" class=\"attachment-full size-full wp-image-3094\" alt=\"biodegradowalne pude\u0142ko na lunch\" srcset=\"https:\/\/jinruipaper.com\/wp-content\/uploads\/2024\/06\/humbruger-clamshell-1-1.jpg 800w, https:\/\/jinruipaper.com\/wp-content\/uploads\/2024\/06\/humbruger-clamshell-1-1-300x293.jpg 300w, https:\/\/jinruipaper.com\/wp-content\/uploads\/2024\/06\/humbruger-clamshell-1-1-768x750.jpg 768w, https:\/\/jinruipaper.com\/wp-content\/uploads\/2024\/06\/humbruger-clamshell-1-1-12x12.jpg 12w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ade6bc4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ade6bc4\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6525df3\" data-id=\"6525df3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1620a60 elementor-widget elementor-widget-text-editor\" data-id=\"1620a60\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>4. Materia\u0142y budowlane:<\/p><p>Kompozyty wzmocnione w\u0142\u00f3knem: W\u0142\u00f3kna pulpy bambusowej mog\u0105 zwi\u0119ksza\u0107 wytrzyma\u0142o\u015b\u0107 i wytrzyma\u0142o\u015b\u0107 tworzyw sztucznych, betonu i innych materia\u0142\u00f3w, odpowiednich do wytwarzania p\u0142yt z tworzyw sztucznych wzmocnionych w\u0142\u00f3knem i pod\u0142\u00f3g kompozytowych.<\/p><p>Lekkie panele budowlane: W\u0142\u00f3kna masy celulozowej bambusa mo\u017cna wykorzysta\u0107 do tworzenia lekkich i wytrzyma\u0142ych paneli budowlanych na \u015bciany, sufity i inne cz\u0119\u015bci budynk\u00f3w, zapewniaj\u0105c dobr\u0105 izolacj\u0119 i d\u017awi\u0119koszczelno\u015b\u0107<\/p><p>5. Produkty medyczne: Miazga bambusowa s\u0142u\u017cy do wytwarzania wytrzyma\u0142ych jednorazowych produkt\u00f3w medycznych, kt\u00f3re mo\u017cna \u0142atwo szybko wyrzuci\u0107, co zmniejsza ryzyko infekcji i zmniejsza zu\u017cycie plastiku. Niekt\u00f3rzy z naszych klient\u00f3w u\u017cywaj\u0105 bielonej pulpy bambusowej do produkcji artyku\u0142\u00f3w medycznych, takich jak naczynia nerkowe, miski do mycia, butelki do pisuaru i baseny.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-431400b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"431400b\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2026dcb\" data-id=\"2026dcb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec16ced elementor-widget elementor-widget-image\" data-id=\"ec16ced\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"480\" src=\"https:\/\/jinruipaper.com\/wp-content\/uploads\/2024\/06\/762-650_M_XL__22752-1-768x480.jpg\" class=\"attachment-medium_large size-medium_large wp-image-3093\" alt=\"Naczynie nerkowe z masy papierowej\" srcset=\"https:\/\/jinruipaper.com\/wp-content\/uploads\/2024\/06\/762-650_M_XL__22752-1-768x480.jpg 768w, https:\/\/jinruipaper.com\/wp-content\/uploads\/2024\/06\/762-650_M_XL__22752-1-300x188.jpg 300w, https:\/\/jinruipaper.com\/wp-content\/uploads\/2024\/06\/762-650_M_XL__22752-1-18x12.jpg 18w, https:\/\/jinruipaper.com\/wp-content\/uploads\/2024\/06\/762-650_M_XL__22752-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3e4e48c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3e4e48c\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6102d1f\" data-id=\"6102d1f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af1b38c elementor-widget elementor-widget-heading\" data-id=\"af1b38c\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">For more information about bamboo pulp, please contact us.<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-83952bb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"83952bb\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-53d719b\" data-id=\"53d719b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b3c7c5 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7b3c7c5\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action:action=popup:open&settings=eyJpZCI6IjQyMyIsInRvZ2dsZSI6ZmFsc2V9\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Zapytanie<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1408ba4\" data-id=\"1408ba4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7792ddc elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7792ddc\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/api.whatsapp.com\/send?phone=8615680886387\" target=\"_blank\" rel=\"nofollow noopener\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">WhatsApp<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Strona g\u0142\u00f3wna Do czego wykorzystuje si\u0119 bambusow\u0105 mas\u0119 papierow\u0105? Bambusowa masa papiernicza to rodzaj masy celulozowej wykonanej z materia\u0142\u00f3w bambusowych, takich jak bambus Mao, bambus Nan i bambus Ci. Nasza fabryka wykorzystuje do jego produkcji metod\u0119 siarczanow\u0105. Miazga bambusowa ma \u015bredniej d\u0142ugo\u015bci w\u0142\u00f3kna, jest delikatna i mi\u0119kka. Arkusze miazgi s\u0105 grube i\u2026<\/p>","protected":false},"author":1,"featured_media":615,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[1],"tags":[115,15,201],"class_list":["post-3078","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-bamboo-paper","tag-bamboo-pulp","tag-what-is-bamboo-pulp-used-for"],"_links":{"self":[{"href":"https:\/\/jinruipaper.com\/pl\/wp-json\/wp\/v2\/posts\/3078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jinruipaper.com\/pl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jinruipaper.com\/pl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jinruipaper.com\/pl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jinruipaper.com\/pl\/wp-json\/wp\/v2\/comments?post=3078"}],"version-history":[{"count":0,"href":"https:\/\/jinruipaper.com\/pl\/wp-json\/wp\/v2\/posts\/3078\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jinruipaper.com\/pl\/wp-json\/wp\/v2\/media\/615"}],"wp:attachment":[{"href":"https:\/\/jinruipaper.com\/pl\/wp-json\/wp\/v2\/media?parent=3078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jinruipaper.com\/pl\/wp-json\/wp\/v2\/categories?post=3078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jinruipaper.com\/pl\/wp-json\/wp\/v2\/tags?post=3078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}